{"id":248105,"date":"2024-03-29T10:12:54","date_gmt":"2024-03-29T17:12:54","guid":{"rendered":"https:\/\/www.zuora.com\/2024\/03\/29\/tirer-parti-des-donnees-proprietaires-pour-la-croissance-de-laudience-et-la-personnalisation\/"},"modified":"2024-04-17T08:59:28","modified_gmt":"2024-04-17T15:59:28","slug":"leveraging-first-party-data-for-audience-growth-and-personalization","status":"publish","type":"post","link":"https:\/\/www.zuora.com\/fr\/2024\/03\/29\/leveraging-first-party-data-for-audience-growth-and-personalization\/","title":{"rendered":"Tirer parti des donn\u00e9es propri\u00e9taires pour la croissance de l&rsquo;audience et la personnalisation"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">La qu\u00eate de l&rsquo;augmentation de l&rsquo;audience est devenue de plus en plus complexe, mais la solution reste ancr\u00e9e dans quelque chose de tout \u00e0 fait fondamental : les donn\u00e9es. Pas n&rsquo;importe quelles donn\u00e9es, mais les donn\u00e9es propri\u00e9taires, un v\u00e9ritable tr\u00e9sor d&rsquo;informations directement issues de votre audience. Alors que nous naviguons dans ce monde post-cookie, comprendre et utiliser les donn\u00e9es propri\u00e9taires n&rsquo;a jamais \u00e9t\u00e9 aussi crucial. Le changement dans l&rsquo;\u00e9cosyst\u00e8me num\u00e9rique, s&rsquo;\u00e9loignant des cookies tiers, a propuls\u00e9 les donn\u00e9es propri\u00e9taires du statut de \u00ab\u00a0bon \u00e0 avoir\u00a0\u00bb \u00e0 celui de n\u00e9cessit\u00e9 pour les entreprises cherchant \u00e0 prosp\u00e9rer en ligne.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u00c0 l&rsquo;avant-garde de ce changement, <\/span><a href=\"https:\/\/www.thinkwithgoogle.com\/future-of-marketing\/digital-transformation\/sustainable-first-party-data-strategy\/\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400;\">Google dit<\/span><\/a><span style=\"font-weight: 400;\">: \u201c<\/span><i><span style=\"font-weight: 400;\">Contrairement aux donn\u00e9es tierces qui sont souvent disponibles pour de nombreuses entreprises diff\u00e9rentes, les donn\u00e9es propri\u00e9taires sont uniques \u00e0 votre entreprise&#8230; Nous avons constat\u00e9 que ceux qui utilisent des donn\u00e9es propri\u00e9taires pour des fonctions marketing cl\u00e9s ont r\u00e9alis\u00e9 jusqu&rsquo;\u00e0 2,9 fois plus de revenus et une \u00e9conomie de co\u00fbts augment\u00e9e de 1,5 fois. Malgr\u00e9 ses avantages \u00e9vidents, cependant, la plupart des marques n&rsquo;exploitent pas encore pleinement le potentiel des donn\u00e9es propri\u00e9taires.<\/span><\/i><span style=\"font-weight: 400;\">\u201d<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Avec <\/span><a href=\"https:\/\/www.zuora.com\/guides\/how-publishers-can-use-first-party-data-for-programmatic-advertising\/#:~:text=A%20statistic%20confirmed%20by%20another,shaking%20up%20the%20marketing%20world.\"><span style=\"font-weight: 400;\">81 % des marketeurs<\/span><\/a><span style=\"font-weight: 400;\"> en signalant leur retour sur investissement le plus \u00e9lev\u00e9 lors de l&rsquo;utilisation de donn\u00e9es de premi\u00e8re partie, il est clair que c&rsquo;est un domaine qui n\u00e9cessite une attention significative.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Mais avant de nous plonger dans les tactiques de croissance et les avantages des donn\u00e9es utilisateur, que voulons-nous vraiment dire lorsque nous discutons des diff\u00e9rents types de donn\u00e9es utilisateur ?<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u00a0<\/span><\/p>\n<h2><strong>Types de donn\u00e9es utilisateur<\/strong><\/h2>\n<p><span style=\"font-weight: 400;\">Comprendre les nuances des types de donn\u00e9es, allant des donn\u00e9es de partie z\u00e9ro aux donn\u00e9es de tierce partie, est crucial pour \u00e9laborer des strat\u00e9gies num\u00e9riques efficaces. Avec les pr\u00e9occupations croissantes en mati\u00e8re de confidentialit\u00e9 et la fin imminente des cookies tiers, l&rsquo;accent a \u00e9t\u00e9 d\u00e9plac\u00e9 vers des formes de collecte de donn\u00e9es plus directes et consensuelles. Plongeons dans ce que ces types de donn\u00e9es signifient pour les entreprises et les marketeurs.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><b>Donn\u00e9es de partie z\u00e9ro : la r\u00e9f\u00e9rence en mati\u00e8re de personnalisation<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Cr\u00e9\u00e9es par Forrester Research, les donn\u00e9es z\u00e9ro-partie repr\u00e9sentent le sommet de la collecte de donn\u00e9es, o\u00f9 les clients partagent volontairement leurs informations. Cet \u00e9change volontaire permet aux consommateurs de dicter la mani\u00e8re dont les marques interagissent avec eux, permettant des strat\u00e9gies de marketing hyper-personnalis\u00e9es et des mod\u00e8les d&rsquo;abonnement. Que ce soit \u00e0 travers des quiz, des sondages ou des param\u00e8tres de pr\u00e9f\u00e9rences, les donn\u00e9es z\u00e9ro-partie donnent aux utilisateurs et aux marques des informations pr\u00e9cises et exploitables.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><b>Donn\u00e9es de premi\u00e8re partie : l&rsquo;\u00e9pine dorsale de la compr\u00e9hension de l&rsquo;audience<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Les donn\u00e9es de premi\u00e8re partie concernent toutes les interactions et comportements observ\u00e9s directement sur votre site ou application. Des mod\u00e8les de clics aux dur\u00e9es de session et \u00e0 la fr\u00e9quence d&rsquo;engagement, ces donn\u00e9es offrent une vue d\u00e9taill\u00e9e de l&rsquo;engagement de votre audience. Elles constituent la base de la compr\u00e9hension de vos utilisateurs, permettant un profilage individuel efficace. Des composants essentiels comme les adresses e-mail, les num\u00e9ros de t\u00e9l\u00e9phone et les historiques d&rsquo;achat rel\u00e8vent de cette cat\u00e9gorie, fournissant une ligne directe vers votre audience.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><b>La ligne fine : donn\u00e9es z\u00e9ro vs donn\u00e9es de premi\u00e8re partie<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Faire la distinction entre les donn\u00e9es de z\u00e9ro partie et de premi\u00e8re partie peut \u00eatre subtil. La diff\u00e9rence cl\u00e9 r\u00e9side dans la mani\u00e8re dont les donn\u00e9es sont collect\u00e9es : les donn\u00e9es de z\u00e9ro partie sont fournies librement par les utilisateurs, tandis que les donn\u00e9es de premi\u00e8re partie sont recueillies passivement \u00e0 travers leurs interactions avec votre site. Malgr\u00e9 leurs diff\u00e9rences, les deux types sont directement \u00e9chang\u00e9s de l&rsquo;utilisateur \u00e0 l&rsquo;\u00e9diteur, les donn\u00e9es de z\u00e9ro partie \u00e9tant souvent consid\u00e9r\u00e9es comme un sous-ensemble des donn\u00e9es de premi\u00e8re partie en raison de leur nature consensuelle.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><b>Donn\u00e9es de second partie : \u00c9change de confiance<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Les donn\u00e9es de seconde partie sont essentiellement des donn\u00e9es de premi\u00e8re partie partag\u00e9es entre partenaires de confiance. Elles sont obtenues directement aupr\u00e8s des utilisateurs mais par l&rsquo;interm\u00e9diaire d&rsquo;un tiers. Bien qu&rsquo;elles soient similaires en qualit\u00e9 aux donn\u00e9es de premi\u00e8re partie, la distinction principale r\u00e9side dans la propri\u00e9t\u00e9 et l&rsquo;exclusivit\u00e9 des donn\u00e9es, car elles ne conf\u00e8rent pas de droits exclusifs malgr\u00e9 leur source directe.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><b>Donn\u00e9es de tiers : le g\u00e9ant d\u00e9clinant<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Autrefois pierre angulaire de la publicit\u00e9 num\u00e9rique, les donn\u00e9es tierces sont collect\u00e9es par des entit\u00e9s sans relation directe avec l&rsquo;utilisateur, g\u00e9n\u00e9ralement agr\u00e9g\u00e9es \u00e0 partir de diverses sources. Cependant, leur fiabilit\u00e9 et leur pr\u00e9cision sont en d\u00e9clin, aggrav\u00e9es encore par les r\u00e9glementations sur la vie priv\u00e9e et la suppression progressive des cookies tiers. Ce type de donn\u00e9es, englobant des donn\u00e9es d\u00e9mographiques telles que l&rsquo;\u00e2ge et le revenu, fait face \u00e0 un avenir sombre dans le paysage num\u00e9rique ax\u00e9 sur la confidentialit\u00e9.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><b>Pourquoi les donn\u00e9es de premi\u00e8re partie et de z\u00e9ro partie sont-elles supr\u00eames?<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Le contraste entre les donn\u00e9es de premi\u00e8re et de tierce partie ne pourrait pas \u00eatre plus marqu\u00e9. Les donn\u00e9es de premi\u00e8re partie, collect\u00e9es directement au sein de votre domaine num\u00e9rique, offrent des perspectives uniques que vous poss\u00e9dez exclusivement. En revanche, les donn\u00e9es de tierce partie, largement disponibles \u00e0 l&rsquo;achat, manquent d&rsquo;unicit\u00e9 et de fiabilit\u00e9 par rapport aux sources de donn\u00e9es directes. Dans le climat actuel, o\u00f9 la vie priv\u00e9e est primordiale, les donn\u00e9es de z\u00e9ro et de premi\u00e8re partie se distinguent pour plusieurs raisons. Elles offrent une pr\u00e9cision in\u00e9gal\u00e9e, un rapport qualit\u00e9-prix, et la possibilit\u00e9 d&rsquo;hyper-personnalisation, le tout dans un cadre de collecte transparent et respectueux. Ces types de donn\u00e9es permettent aux entreprises de tisser des relations plus profondes avec leur audience, de personnaliser les exp\u00e9riences et de stimuler les conversions sans les pr\u00e9occupations de confidentialit\u00e9 associ\u00e9es aux donn\u00e9es de tierce partie.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><strong>R\u00e9inventer l&rsquo;engagement du public avec les donn\u00e9es propri\u00e9taires.<\/strong><\/h2>\n<p><span style=\"font-weight: 400;\">Le passage des donn\u00e9es tierces aux insights de premi\u00e8re partie offre une opportunit\u00e9 sans pr\u00e9c\u00e9dent pour les \u00e9diteurs. Cette transition ne consiste pas seulement \u00e0 remplacer une source de donn\u00e9es par une autre ; c&rsquo;est une chance d&rsquo;engager profond\u00e9ment et de se connecter avec les audiences \u00e0 un nouveau niveau. Voici comment les \u00e9diteurs peuvent exploiter tout le potentiel des donn\u00e9es de premi\u00e8re partie pour cr\u00e9er des interactions plus personnalis\u00e9es, plus captivantes et, en fin de compte, plus rentables.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3><b>Cr\u00e9er des entonnoirs d&rsquo;abonnement personnalis\u00e9s<\/b><\/h3>\n<p><span style=\"font-weight: 400;\">Imaginez un monde o\u00f9 chaque lecteur a l&rsquo;impression que votre contenu s&rsquo;adresse directement \u00e0 lui. C&rsquo;est la puissance des donn\u00e9es de premi\u00e8re partie. Elles permettent une plong\u00e9e profonde dans les pr\u00e9f\u00e9rences et comportements uniques de chaque lecteur, permettant des entonnoirs d&rsquo;abonnement qui s&rsquo;adaptent aux int\u00e9r\u00eats individuels. La magie op\u00e8re avec des recommandations de contenu dynamique, et des offres cibl\u00e9es avec des p\u00e9ages qui sont parfaitement chronom\u00e9tr\u00e9s dans le parcours de l&rsquo;utilisateur. En analysant l&rsquo;engagement et l&rsquo;activit\u00e9 des utilisateurs, une entreprise d&rsquo;abonnement peut d\u00e9terminer exactement quand inviter quelqu&rsquo;un \u00e0 un abonnement payant au moment o\u00f9 il est le plus engag\u00e9 et pr\u00eat.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">En utilisant cette tactique pour personnaliser leurs offres d&rsquo;abonnement, <\/span><a href=\"https:\/\/www.zuora.com\/our-customers\/case-studies\/sci\/\"><span style=\"font-weight: 400;\">Client Zuora SCI<\/span><\/a><span style=\"font-weight: 400;\"> a vu un taux de r\u00e9tention des revenus des abonn\u00e9s de plus de 100 %. Dans une veine similaire, <\/span><a href=\"https:\/\/www.zuora.com\/our-customers\/case-studies\/fipp\/\"><span style=\"font-weight: 400;\">FIPP<\/span><\/a><span style=\"font-weight: 400;\"> Ils ont mis en \u0153uvre des parcours d&rsquo;abonnement dynamiques et des murs de paiement, ce qui a entra\u00een\u00e9 un doublement de leurs abonnements totaux 10 jours apr\u00e8s le lancement.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Les recommandations de contenu personnalis\u00e9 aident \u00e9galement \u00e0 maintenir l&rsquo;exp\u00e9rience de lecture fra\u00eeche et captivante, encourageant la fid\u00e9lit\u00e9 et r\u00e9duisant la probabilit\u00e9 de d\u00e9sabonnement. Avec le temps, cette approche ne se contente pas de retenir les abonn\u00e9s ; elle augmente leur valeur \u00e0 vie gr\u00e2ce \u00e0 un engagement continu et des opportunit\u00e9s de vente additionnelle. Avec des r\u00e9sultats comme ceux mentionn\u00e9s ci-dessus, il est clair que la personnalisation a un impact significatif sur les revenus.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3><b>Pr\u00e9voir des opportunit\u00e9s de revenus<\/b><\/h3>\n<p><span style=\"font-weight: 400;\">D\u00e9couvrir et pr\u00e9dire les opportunit\u00e9s de revenus implique d&rsquo;exploiter les donn\u00e9es de premi\u00e8re partie pour identifier les domaines propices \u00e0 la mon\u00e9tisation et au d\u00e9veloppement de produits. Cette approche n\u00e9cessite d&rsquo;analyser les interactions des utilisateurs avec le contenu pour cibler de nouvelles opportunit\u00e9s de revenus, telles que transformer une cat\u00e9gorie de contenu populaire en un service d&rsquo;abonnement premium.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Pour mieux comprendre et pr\u00e9dire quels groupes d&rsquo;utilisateurs et quelles cat\u00e9gories de contenu cibler pour des opportunit\u00e9s de revenus, les entreprises par abonnement pourraient utiliser la mod\u00e9lisation de propension. La mod\u00e9lisation de propension des abonn\u00e9s implique une analyse d\u00e9taill\u00e9e de divers comportements des utilisateurs, allant de l&rsquo;engagement avec les articles aux interactions avec les incitations \u00e0 l&rsquo;abonnement, afin d&rsquo;identifier des motifs indiquant une disposition \u00e0 s&rsquo;abonner. Cette intelligence permet aux entreprises de canaliser leurs efforts de marketing plus efficacement, en se concentrant sur les segments d&rsquo;audience les plus susceptibles de se convertir.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Un excellent exemple de r\u00e9ussite avec la mod\u00e9lisation de propension est <\/span><a href=\"https:\/\/www.zuora.com\/guides\/propensity-modelling-how-publishers-ensure-their-subscription-business-keeps-growing\/\"><span style=\"font-weight: 400;\">L&rsquo;Ind\u00e9pendant<\/span><\/a><span style=\"font-weight: 400;\">qui a exploit\u00e9 la mod\u00e9lisation de propension pour augmenter consid\u00e9rablement son lectorat \u00e0 98 millions de lecteurs par mois.\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<h3><b>Affiner les strat\u00e9gies avec des tests A\/B<\/b><\/h3>\n<p><span style=\"font-weight: 400;\">Les tests A\/B avec des segments d&rsquo;audience constituent une autre m\u00e9thode perspicace pour peaufiner vos strat\u00e9gies d&rsquo;engagement et de conversion. En divisant votre audience sur la base de caract\u00e9ristiques identifi\u00e9es gr\u00e2ce aux donn\u00e9es de premi\u00e8re partie, vous pouvez tester diff\u00e9rents formats de contenu, messages marketing et offres pour voir ce qui r\u00e9sonne le mieux. Ces segments d&rsquo;utilisateurs peuvent \u00eatre d\u00e9finis par des param\u00e8tres tels que les donn\u00e9es d\u00e9mographiques (par exemple, localisation, \u00e2ge), les int\u00e9r\u00eats (par exemple, sports, politique), la fr\u00e9quence d&rsquo;engagement et l&rsquo;\u00e9tat de l&rsquo;utilisateur.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Segmenter un public de cette mani\u00e8re aide non seulement \u00e0 am\u00e9liorer les taux de conversion, mais am\u00e9liore \u00e9galement l&rsquo;exp\u00e9rience utilisateur globale, rendant votre contenu plus pertinent et plus engageant pour chaque lecteur.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">L&rsquo;avantage suppl\u00e9mentaire des segments est que les entreprises peuvent \u00e9galement tester de nouvelles offres \u00e0 petite \u00e9chelle d&rsquo;abord pour voir si elles fonctionnent, avant de les d\u00e9ployer \u00e0 un public plus large. <\/span><a href=\"https:\/\/www.zuora.com\/our-customers\/case-studies\/new-england-newspapers-inc\/\"><span style=\"font-weight: 400;\">New England Newspapers Inc.<\/span><\/a><span style=\"font-weight: 400;\"> ont r\u00e9ussi \u00e0 faire exactement cela, en comprenant mieux leurs utilisateurs en segmentant les audiences et en adaptant les offres en cons\u00e9quence. Cela a entra\u00een\u00e9 une augmentation de 20% des conversions directes de paywall gr\u00e2ce \u00e0 la segmentation et au ciblage des utilisateurs.<\/span><\/p>\n<p>&nbsp;<\/p>\n<h2><strong>P\u00e9rennisez votre croissance<\/strong><\/h2>\n<p><span style=\"font-weight: 400;\">Dans notre discussion, nous avons mis en \u00e9vidence les avantages significatifs et les strat\u00e9gies r\u00e9ussies li\u00e9es \u00e0 l&rsquo;utilisation des donn\u00e9es de premi\u00e8re partie. Le paysage num\u00e9rique actuel se trouve \u00e0 un carrefour crucial, t\u00e9moignant d&rsquo;un changement monumental cette ann\u00e9e, passant de la d\u00e9pendance aux donn\u00e9es de tiers \u00e0 l&rsquo;adoption d&rsquo;une approche ax\u00e9e sur la confidentialit\u00e9 et les donn\u00e9es de premi\u00e8re partie. Cette \u00e9volution souligne une nouvelle \u00e8re dans l&rsquo;engagement num\u00e9rique, o\u00f9 la priorisation de la confidentialit\u00e9 des utilisateurs et l&rsquo;offre de contenu personnalis\u00e9 deviennent la norme. Les \u00e9diteurs pr\u00eats \u00e0 adopter et \u00e0 g\u00e9rer les donn\u00e9es de premi\u00e8re partie se positionnent \u00e0 l&rsquo;avant-garde de ce changement. La cl\u00e9 de leur succ\u00e8s r\u00e9side dans la construction de relations directes et respectueuses avec leur audience, offrant des exp\u00e9riences personnalis\u00e9es qui respectent la vie priv\u00e9e des utilisateurs, et se d\u00e9marquant ainsi dans un monde post-cookie en rapide \u00e9volution.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">La transition vers les donn\u00e9es propri\u00e9taires pr\u00e9sente des d\u00e9fis significatifs mais offre \u00e9galement des opportunit\u00e9s encore plus grandes. Le d\u00e9fi : red\u00e9finir l&rsquo;engagement de l&rsquo;audience en l&rsquo;absence de donn\u00e9es tierces. L&rsquo;opportunit\u00e9 : favoriser des relations transparentes et emplies de confiance avec les audiences, menant \u00e0 une loyaut\u00e9 et un engagement accrus. Ce changement vers une approche ax\u00e9e sur la confidentialit\u00e9 et la personnalisation n&rsquo;est pas seulement b\u00e9n\u00e9fique, mais essentiel pour les \u00e9diteurs qui souhaitent rester comp\u00e9titifs et pertinents.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La qu\u00eate de l&rsquo;augmentation de l&rsquo;audience est devenue de plus en plus complexe, mais la solution reste ancr\u00e9e dans quelque chose de tout \u00e0 fait fondamental : les donn\u00e9es. Pas n&rsquo;importe quelles donn\u00e9es, mais les donn\u00e9es propri\u00e9taires, un v\u00e9ritable tr\u00e9sor d&rsquo;informations directement issues de votre audience. Alors que nous naviguons dans ce monde post-cookie, comprendre [&hellip;]<\/p>\n","protected":false},"author":227,"featured_media":246268,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[32928],"tags":[],"content_type":[33421],"industry":[33422],"persona":[32985],"product_line":[33231],"topic":[33423],"class_list":["post-248105","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classifiee","content_type-blog-fr","industry-medias-and-entertainment-fr","persona-marketing-fr","product_line-zephr-fr","topic-subscriber-acquisition-and-retention-fr"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.zuora.com\/fr\/wp-json\/wp\/v2\/posts\/248105","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zuora.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.zuora.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.zuora.com\/fr\/wp-json\/wp\/v2\/users\/227"}],"replies":[{"embeddable":true,"href":"https:\/\/www.zuora.com\/fr\/wp-json\/wp\/v2\/comments?post=248105"}],"version-history":[{"count":0,"href":"https:\/\/www.zuora.com\/fr\/wp-json\/wp\/v2\/posts\/248105\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.zuora.com\/fr\/wp-json\/wp\/v2\/media\/246268"}],"wp:attachment":[{"href":"https:\/\/www.zuora.com\/fr\/wp-json\/wp\/v2\/media?parent=248105"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.zuora.com\/fr\/wp-json\/wp\/v2\/categories?post=248105"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.zuora.com\/fr\/wp-json\/wp\/v2\/tags?post=248105"},{"taxonomy":"content_type","embeddable":true,"href":"https:\/\/www.zuora.com\/fr\/wp-json\/wp\/v2\/content_type?post=248105"},{"taxonomy":"industry","embeddable":true,"href":"https:\/\/www.zuora.com\/fr\/wp-json\/wp\/v2\/industry?post=248105"},{"taxonomy":"persona","embeddable":true,"href":"https:\/\/www.zuora.com\/fr\/wp-json\/wp\/v2\/persona?post=248105"},{"taxonomy":"product_line","embeddable":true,"href":"https:\/\/www.zuora.com\/fr\/wp-json\/wp\/v2\/product_line?post=248105"},{"taxonomy":"topic","embeddable":true,"href":"https:\/\/www.zuora.com\/fr\/wp-json\/wp\/v2\/topic?post=248105"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}