{"id":203985,"date":"2022-07-26T06:00:49","date_gmt":"2022-07-26T13:00:49","guid":{"rendered":"https:\/\/sboxtest.zuora.com\/products\/zuora-central-platform\/secure-data-share-for-snowflake\/"},"modified":"2025-12-01T09:42:03","modified_gmt":"2025-12-01T17:42:03","slug":"secure-data-share-for-snowflake","status":"publish","type":"page","link":"https:\/\/www.zuora.com\/fr\/solutions\/zuora-platform\/secure-data-share-for-snowflake\/","title":{"rendered":"Zuora Secure Data Share pour Snowflake"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"203985\" class=\"elementor elementor-203985 elementor-127105\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-11bed81 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"11bed81\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9560f76\" data-id=\"9560f76\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b2967e0 elementor-widget elementor-widget-text-editor\" data-id=\"b2967e0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>ZUORA\u00a0PLATFORM\u00a0\u2013 Secure Data Share for Snowflake<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0e8f71e elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"0e8f71e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Lib\u00e9rez tout le potentiel de vos donn\u00e9es pour acc\u00e9l\u00e9rer vos d\u00e9cisions strat\u00e9giques<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-61ea105 elementor-widget elementor-widget-text-editor\" data-id=\"61ea105\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Zuora Secure Data Share for Snowflake \u00e9limine les d\u00e9veloppements fastidieux et transf\u00e8re rapidement vos donn\u00e9es Zuora dans Snowflake. Ce module donne \u00e0 votre \u00e9quipe la possibilit\u00e9 d\u2019utiliser sa propre BI pour les m\u00e9triques inter-syst\u00e8mes, tout en tirant un trait sur les builds d\u2019int\u00e9gration et la maintenance continue.<\/p>\n<p>D\u00e9veloppez une vue \u00e0 360\u00b0 sur les parcours clients avec toutes leurs donn\u00e9es rassembl\u00e9es au m\u00eame endroit.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e161b88 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e161b88\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5b8412f\" data-id=\"5b8412f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-52bb3c5 elementor-section-full_width elementor-section-height-min-height elementor-section-content-middle elementor-section-height-default\" data-id=\"52bb3c5\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-fac62e7\" data-id=\"fac62e7\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7c83540 elementor-widget elementor-widget-html\" data-id=\"7c83540\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<script type=\"text\/javascript\" id=\"vidyard_embed_code_WvBaKRuSKPv1RHTt3FwJEk\" src=\"\/\/play.vidyard.com\/WvBaKRuSKPv1RHTt3FwJEk.js?v=3.1.1&amp;type=lightbox\"><\/script>\n                  <div class=\"z-video-button\" onclick=\"fn_vidyard_WvBaKRuSKPv1RHTt3FwJEk();\">\n                      <img decoding=\"async\" src=\"https:\/\/www.zuora.com\/wp-content\/uploads\/2022\/04\/zds-Play-Button.svg\" id=\"playbutton\" class=\"video-button\" \/>\n                      <\/div>\n \n              \n              \n\n              \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d69f4c1 elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default\" data-id=\"d69f4c1\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0683b00\" data-id=\"0683b00\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5493d30 elementor-widget__width-auto elementor-widget elementor-widget-heading\" data-id=\"5493d30\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/www.zuora.com\/fr\/talk-to-sales\/\">Pr\u00eat \u00e0 en savoir plus\u00a0? Contactez votre CSM d\u00e8s aujourd\u2019hui pour entamer le dialogue.<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f409814 elementor-widget__width-auto elementor-widget elementor-widget-button\" data-id=\"f409814\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.zuora.com\/fr\/talk-to-sales\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-arrow-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Parlez \u00e0 un expert<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-351e699 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"351e699\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-747a51e\" data-id=\"747a51e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-776d506 elementor-widget-mobile__width-initial elementor-widget elementor-widget-image\" data-id=\"776d506\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"855\" height=\"738\" src=\"https:\/\/www.zuora.com\/wp-content\/uploads\/2022\/04\/zds-j2u-img-2.png\" class=\"attachment-full size-full wp-image-184781\" alt=\"\" srcset=\"https:\/\/www.zuora.com\/wp-content\/uploads\/2022\/04\/zds-j2u-img-2.png 855w, https:\/\/www.zuora.com\/wp-content\/uploads\/2022\/04\/zds-j2u-img-2-640x552.png 640w, https:\/\/www.zuora.com\/wp-content\/uploads\/2022\/04\/zds-j2u-img-2-768x663.png 768w\" sizes=\"(max-width: 855px) 100vw, 855px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-6e247ed\" data-id=\"6e247ed\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-e3a559f elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"e3a559f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-9f51ba2\" data-id=\"9f51ba2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a74b69b elementor-widget elementor-widget-heading\" data-id=\"a74b69b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">The Journey to Usership<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-515e60d elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"515e60d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Un mod\u00e8le au service de la modernisation,\nla mon\u00e9tisation et l\u2019\u00e9volution de votre entreprise<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0a8cfbf elementor-widget elementor-widget-spacer\" data-id=\"0a8cfbf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ff467f4 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"ff467f4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Alors que vos clients \u00e9voluent dans leur mani\u00e8re d\u2019acc\u00e9der \u00e0 vos produits et services, vous devez de m\u00eame \u00e9voluer dans la mani\u00e8re de mener vos activit\u00e9s. Baptis\u00e9 The Journey to Usership\u2122, notre playbook d\u2019expertise et de ressources accompagne la r\u00e9ussite d\u2019entreprises du monde entier op\u00e9rant sur un mod\u00e8le d\u2019abonnements.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-67272b2 elementor-widget elementor-widget-button\" data-id=\"67272b2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.zuora.com\/fr\/journey-to-usership\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-arrow-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">En savoir plus<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b56bbb8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b56bbb8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c032d21\" data-id=\"c032d21\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b07a238 elementor-widget elementor-widget-eael-lightbox\" data-id=\"b07a238\" data-element_type=\"widget\" data-e-type=\"widget\" id=\"open-popup\" data-widget_type=\"eael-lightbox.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\n\t\t<div data-lightbox-type=\"lightbox_type_template\" data-lightbox-type-url=\"\" data-lightbox-trigger-pageload=\"1\" data-lightbox-closebtn-color=\"#ffffff\" class=\"eael-lightbox-wrapper\" data-trigger=\"eael_lightbox_trigger_external\" data-lightbox-id=\"lightbox_6a57494c26e39\" data-type=\"inline\" data-src=\"#eael-lightbox-window-6a57494c26e39\" data-popup-layout=\"eael-lightbox-popup-standard\" data-main-class=\"eael-lightbox-modal-popup-b07a238\" data-close_button=\"yes\" data-esc_exit=\"yes\" data-click_exit=\"yes\" data-effect=\"animated \" data-trigger-element=\"#open-popup\">\n\t\t\t<div class=\"eael-lightbox-btn\">\n\t\t\t\t\t\t\t<\/div><!-- close .eael-lightbox-btn -->\n\t\t<\/div>\n\n\t\t<div class=\"eael-lightbox-popup-window eael-lightbox-popup-window-b07a238 lightbox_type_template\" id=\"eael-lightbox-window-6a57494c26e39\">\n\t\t\t<div class=\"eael-lightbox-container\">\n\t\t\t\t<style>.elementor-192914 .elementor-element.elementor-element-675de3ff > .elementor-container{max-width:800px;}.elementor-192914 .elementor-element.elementor-element-675de3ff:not(.elementor-motion-effects-element-type-background), .elementor-192914 .elementor-element.elementor-element-675de3ff > .elementor-motion-effects-container > .elementor-motion-effects-layer{background-color:#FFFFFF;}.elementor-192914 .elementor-element.elementor-element-675de3ff{transition:background 0.3s, border 0.3s, border-radius 0.3s, box-shadow 0.3s;margin-top:15.5%;margin-bottom:0%;padding:20px 20px 20px 20px;}.elementor-192914 .elementor-element.elementor-element-675de3ff > .elementor-background-overlay{transition:background 0.3s, border-radius 0.3s, opacity 0.3s;}.elementor-192914 .elementor-element.elementor-element-17c2ce55 > .elementor-element-populated{padding:0px 0px 0px 40px;}.elementor-192914 .elementor-element.elementor-element-cbf03d9{text-align:start;}.elementor-192914 .elementor-element.elementor-element-cbf03d9 img{width:80%;}.elementor-192914 .elementor-element.elementor-element-97dc665{text-align:start;}.elementor-192914 .elementor-element.elementor-element-97dc665 .elementor-heading-title{font-family:\"Founders Grotesk\", Sans-serif;font-size:40px;font-weight:600;text-transform:uppercase;line-height:40px;color:#072C4B;}.elementor-192914 .elementor-element.elementor-element-97dc665 > .elementor-widget-container{margin:0px 0px 0px 0px;}.elementor-192914 .elementor-element.elementor-element-1bb4b72 > .elementor-widget-container{padding:0px 0px 0px 0px;}@media(max-width:767px){.elementor-192914 .elementor-element.elementor-element-97dc665 .elementor-heading-title{font-size:26px;}.elementor-192914 .elementor-element.elementor-element-f85b30e > .elementor-element-populated{margin:30px 0px 0px 0px;--e-column-margin-right:0px;--e-column-margin-left:0px;}}@media(min-width:768px){.elementor-192914 .elementor-element.elementor-element-17c2ce55{width:50%;}.elementor-192914 .elementor-element.elementor-element-f85b30e{width:50%;}}\/* Start custom CSS *\/.mfp-content .eael-lightbox-popup-window{width:800px;}\n.mfp-close{position: absolute !important;\n    top: 20px;\n    left: 2px;\n    width: 30px;\n    height: 30px;\n    cursor: pointer;\n    background-image: url(https:\/\/play.vidyard.com\/close.png);\n    background-repeat: no-repeat;\n    background-position: 2px 2px;\n    background-color: rgba(0,0,0,0);\n    border: none;\n    opacity: 0.75;\n    padding: 0;\n    color: transparent !important;}\/* End custom CSS *\/\n\/* Start Custom Fonts CSS *\/@font-face {\n\tfont-family: 'Founders Grotesk';\n\tfont-style: normal;\n\tfont-weight: 700;\n\tfont-display: auto;\n\tsrc: url('https:\/\/nav-assets.zuora.life\/v2\/fonts\/fonts\/founders-grotesk\/bold.woff2') format('woff2');\n}\n@font-face {\n\tfont-family: 'Founders Grotesk';\n\tfont-style: normal;\n\tfont-weight: 600;\n\tfont-display: auto;\n\tsrc: url('https:\/\/nav-assets.zuora.life\/v2\/fonts\/fonts\/founders-grotesk\/semibold.woff2') format('woff2');\n}\n@font-face {\n\tfont-family: 'Founders Grotesk';\n\tfont-style: normal;\n\tfont-weight: 500;\n\tfont-display: auto;\n\tsrc: url('https:\/\/nav-assets.zuora.life\/v2\/fonts\/fonts\/founders-grotesk\/medium.woff2') format('woff2');\n}\n@font-face {\n\tfont-family: 'Founders Grotesk';\n\tfont-style: normal;\n\tfont-weight: 400;\n\tfont-display: auto;\n\tsrc: url('https:\/\/nav-assets.zuora.life\/v2\/fonts\/fonts\/founders-grotesk\/regular.woff2') format('woff2');\n}\n@font-face {\n\tfont-family: 'Founders Grotesk';\n\tfont-style: normal;\n\tfont-weight: 300;\n\tfont-display: auto;\n\tsrc: url('https:\/\/nav-assets.zuora.life\/v2\/fonts\/fonts\/founders-grotesk\/light.woff2') format('woff2');\n}\n\/* End Custom Fonts CSS *\/<\/style>\t\t<div data-elementor-type=\"page\" data-elementor-id=\"192914\" class=\"elementor elementor-192914 elementor-121938 elementor-121938\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-675de3ff J2Uform elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"675de3ff\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-17c2ce55 elementor-hidden-phone\" data-id=\"17c2ce55\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cbf03d9 elementor-widget elementor-widget-image\" data-id=\"cbf03d9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/www.zuora.com\/wp-content\/uploads\/2022\/04\/Unlock-event-lockup-logov2.svg\" class=\"attachment-large size-large wp-image-323246\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-97dc665 register-form-callout elementor-hidden-phone elementor-widget elementor-widget-heading\" data-id=\"97dc665\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Regardez maintenant\n<span> &gt;&gt;<\/span><i><\/i><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-f85b30e\" data-id=\"f85b30e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1bb4b72 elementor-widget elementor-widget-z-marketo-form2\" data-id=\"1bb4b72\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"z-marketo-form2.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<div class=\"container-fluid marketo-form-container MarketoFormContainer\">\n                                    <div class=\"form-wrapper marketo-form \"\n                 style=\"\"\n                 data-marketo_id=\"4874\"\n                 data-is_multistep=\"\"\n                 data-ty_url=\"#\"\n                 data-cid=\"FY23Q1_EVENT-CORP_GLOBL_EVENT_Zuora-Unlock-On-Demand\"\n                 data-language=\"\"\n                 data-form-style=\"default\"\n                 data-multiple_forms=\"\"\n            >\n                <section class=\"form mkto-form \">\n\n                    <!-- FORM LOGO -->\n                    \n                    <!--\n                        Not ideal, but this is \"clean\" why to override the CSS in Marketo Forms.\n                        @link https:\/\/nation.marketo.com\/t5\/product-discussions\/what-is-the-best-approach-to-overriding-the-css-in-marketo-forms\/td-p\/327302\n                    -->\n                    \n                                        <!-- FORM BODY -->\n                    <form id=\"mktoForm_4874\"\n                          data-button-text=\"\"\n                          class=\"is-noColumns                                default                                has-noBackground                                has-noFormIcons                                has-noButtonCornersChange                                has-noButtonColorChange                                has-noButtonIcon                                has-noButtonDynamicText                                has-noButtonWidthChange\"\n                    >\n                        \n                        \n                        <!-- FORM-FIELDS -->\n                        <span data-anchor><\/span>\n                    <\/form>\n\n                    <!-- MULTI-STEP-CONTROLS -->\n                    \n                                    <\/section>\n\n                \n<section class=\"thankyou hide MarketoForm-thankYouSection\">\n\n    <div class=\"headline\">\n        <h3>Thanks for your response!<\/h3>\n        <h4>We'll get back to shortly.<\/h4>\n    <\/div>\n\n    \n    \n<\/section>\n\n\n\n            <\/div>\n            <\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-52d2f64 elementor-widget elementor-widget-html\" data-id=\"52d2f64\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<script>\n\/\/****** Add Listener for vidyard playbutton click() - This listener checks if form is already filled out by user and if so autostarts video if not pops form up in modal ***********\ndocument.querySelector('.vidyard_wrapper').addEventListener(\"click\", \n    (e)=>{\n    e.preventDefault();\n    var filledForm = window.localStorage.getItem('UnlockComplete');\n    viduidCB(e); \n   if(!filledForm){document.getElementById('open-popup').click();}\n   else{var autoStartVideo = window.localStorage.getItem('puidClickbait');window[autoStartVideo]();}\n});\n\/\/****** Add Listener for marketo form - This listener sets form filed tags in the users' local storage and pops form up in modal, submits data, and auto starts video playback ***********\ndocument.querySelector('#mktoForm_1871').addEventListener(\"submit\", (e)=>{\n    generateLeadForm();\n    document.querySelector('.mfp-close').click();\n});\n\/\/****** Fuctions call Store Video function Nomenclature () - This stores vidyard unique ID for click function ***********\nfunction viduidCB(element){\n  var ppuid = element.currentTarget.previousElementSibling.id.replace(\/.*_\\w*(_)\/g,\"\");\n   var puidClickbait = \"fn_vidyard_\"+ppuid;\n   window.localStorage.setItem('puidClickbait',puidClickbait);  \n}\n\/\/****** Fuctions call Generate Lead Form () - Start Video ***********\nfunction generateLeadForm(){\nwindow.localStorage.setItem('UnlockComplete',true);\n\nvar form = document.querySelector(\"#mktoForm_1871\");\nMktoForms2.whenReady(function (form){\nform.submit();\nform.onSuccess(function(vals,thanksURL){\n    return false;\n  });\n});\nvar autoStartVideo = window.localStorage.getItem('puidClickbait');\nwindow[autoStartVideo]();\n}\/\/End onSuccess\n<\/script>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6202b4f elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default\" data-id=\"6202b4f\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1d39f5b\" data-id=\"1d39f5b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a1ff7bb elementor-widget elementor-widget-template\" data-id=\"a1ff7bb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<div data-elementor-type=\"page\" data-elementor-id=\"195223\" class=\"elementor elementor-195223 elementor-119136 elementor-119136\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7a4ca65 elementor-section-stretched elementor-reverse-tablet elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7a4ca65\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-d756d51\" data-id=\"d756d51\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e44e2c9 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"e44e2c9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Inspirez-vous des meilleurs<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-eba37bb elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"eba37bb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">D\u00e9veloppez votre potentiel avec nos experts<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4644d69 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"4644d69\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Nous sommes les leaders incontournable sur le march\u00e9 de l&rsquo;abonnement et de l&rsquo;usage. Ensemble, allons plus loin. Apprenez de nos experts, de nos clients et de nos partenaires.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-d450ccf\" data-id=\"d450ccf\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b5482c4 elementor-widget elementor-widget-image\" data-id=\"b5482c4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.zuora.com\/wp-content\/uploads\/2023\/09\/zds-buildrungrow-2.svg\" class=\"attachment-full size-full wp-image-227791\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-0469c94 e-flex e-con-boxed e-con e-parent\" data-id=\"0469c94\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-dd0a5ab e-con-full e-flex e-con e-child\" data-id=\"dd0a5ab\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-731ae56 e-con-full e-flex e-con e-child\" data-id=\"731ae56\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3c6260f fal elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"3c6260f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"fal fa-coins\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c31c203 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"c31c203\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Nouveaux Business Models<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-85988b3 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"85988b3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tGuidez vos clients tout au long de leur parcour. \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-84e2471 elementor-position-inline-end no-border-btn elementor-view-default elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"84e2471\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"https:\/\/www.zuora.com\/fr\/journey-to-usership\/business-initiatives\/\" class=\"elementor-icon\" tabindex=\"-1\" aria-label=\"Explorer les opportunit\u00e9s commerciales\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-arrow-right\"><\/i>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<a href=\"https:\/\/www.zuora.com\/fr\/journey-to-usership\/business-initiatives\/\" >\n\t\t\t\t\t\t\tExplorer les opportunit\u00e9s commerciales\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-468639c e-con-full e-flex e-con e-child\" data-id=\"468639c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-3ad6009 e-con-full e-flex e-con e-child\" data-id=\"3ad6009\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c53dfb2 fal elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"c53dfb2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"fal fa-layer-group\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9d51ec1 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"9d51ec1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">La Communaut\u00e9 Zuora<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-56d47f3 elementor-widget__width-initial elementor-widget-mobile__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"56d47f3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\u00c9changez avec nos experts.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3aff0c6 elementor-position-inline-end no-border-btn elementor-view-default elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"3aff0c6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"https:\/\/community.zuora.com\/\" class=\"elementor-icon\" tabindex=\"-1\" aria-label=\"D\u00e9couvrez notre communaut\u00e9\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-arrow-right\"><\/i>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<a href=\"https:\/\/community.zuora.com\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\tD\u00e9couvrez notre communaut\u00e9\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0e915c4 e-con-full e-flex e-con e-child\" data-id=\"0e915c4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-0d33016 e-con-full e-flex e-con e-child\" data-id=\"0d33016\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a45df37 fal elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"a45df37\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"fal fa-project-diagram\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1db11b9 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"1db11b9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Ressources pour les d\u00e9veloppeurs<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7b9e142 elementor-widget__width-initial elementor-widget-mobile__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"7b9e142\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tInnovez en toute libert\u00e9 avec les produits Zuora.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bf402b7 elementor-position-inline-end no-border-btn elementor-view-default elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"bf402b7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"\/developer\/\" class=\"elementor-icon\" tabindex=\"-1\" aria-label=\"Explorez le Developer Center\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-arrow-right\"><\/i>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<a href=\"\/developer\/\" >\n\t\t\t\t\t\t\tExplorez le Developer Center\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-aa24c12 e-con-full e-flex e-con e-child\" data-id=\"aa24c12\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-4abbf79 e-con-full e-flex e-con e-child\" data-id=\"4abbf79\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-384d782 fal elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"384d782\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"fal fa-book\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5e1d060 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"5e1d060\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Ressources<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1974aa4 elementor-widget__width-initial elementor-widget-tablet__width-initial elementor-widget-mobile__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"1974aa4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>D\u00e9couvrez comment d\u00e9velopper votre entreprise \u00e0 l&rsquo;\u00e8re des abonnements.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1354035 elementor-position-inline-end no-border-btn elementor-view-default elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"1354035\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"https:\/\/knowledgecenter.zuora.com\/\" class=\"elementor-icon\" tabindex=\"-1\" aria-label=\"Explorez nos ressources\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-arrow-right\"><\/i>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<a href=\"https:\/\/knowledgecenter.zuora.com\/\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t\tExplorez nos ressources\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2ca7281 elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default\" data-id=\"2ca7281\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-57c54a5\" data-id=\"57c54a5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ba0af98 elementor-widget elementor-widget-template\" data-id=\"ba0af98\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<div data-elementor-type=\"page\" data-elementor-id=\"194823\" class=\"elementor elementor-194823 elementor-119153 elementor-119153\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ffc0967 e-flex e-con-boxed e-con e-parent\" data-id=\"ffc0967\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-ef44a7c e-con-full e-flex e-con e-child\" data-id=\"ef44a7c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4b98a2b elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"4b98a2b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Optez pour le succ\u00e8s r\u00e9current<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fa40fcb elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"fa40fcb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Les entreprises s\u2019appuient sur Zuora pour accompagner leur croissance. Parce que votre succ\u00e8s est aussi le n\u00f4tre, nous avons \u00e0 c\u0153ur de r\u00e9pondre \u00e0 vos plus grands d\u00e9fis. Notre technologie s\u2019adapte \u00e0 votre mod\u00e8le \u00e9conomique, quel qu\u2019il soit : par abonnement, \u00e0 la consommation, \u00e0 l\u2019usage, hybride, \u2026 A nos c\u00f4t\u00e9s, mon\u00e9tisez l\u2019int\u00e9gralit\u00e9 de vos services.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-40cbdfe e-flex e-con-boxed e-con e-child\" data-id=\"40cbdfe\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-500ef5d elementor-widget__width-auto elementor-widget elementor-widget-button\" data-id=\"500ef5d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"\/fr\/resources\/demo-on-demand\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir une d\u00e9mo<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-289bfe7 elementor-widget__width-auto elementor-widget elementor-widget-button\" data-id=\"289bfe7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"\/fr\/talk-to-sales\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Parler \u00e0 un expert<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3b22a68 e-con-full e-flex e-con e-child\" data-id=\"3b22a68\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-f6f141c e-flex e-con-boxed e-con e-child\" data-id=\"f6f141c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-1ce8245 e-con-full e-flex e-con e-child\" data-id=\"1ce8245\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-addadb5 e-flex e-con-boxed e-con e-child\" data-id=\"addadb5\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c1a01ae elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"c1a01ae\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Envie de mener le changement?<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-eab30f0 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"eab30f0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Int\u00e9grez notre \u00e9quipe internationale d\u00e9di\u00e9e \u00e0 la m\u00e9tamorphose des entreprises leaders \u00e0 l&rsquo;\u00e9chelle globale.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8c2afe7 elementor-position-inline-end elementor-widget__width-auto elementor-view-default elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"8c2afe7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"\/fr\/careers\/\" class=\"elementor-icon\" tabindex=\"-1\" aria-label=\"Explorer vos opportunit\u00e9s\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-arrow-right\"><\/i>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<a href=\"\/fr\/careers\/\" >\n\t\t\t\t\t\t\tExplorer vos opportunit\u00e9s\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>ZUORA\u00a0PLATFORM\u00a0\u2013 Secure Data Share for Snowflake Lib\u00e9rez tout le potentiel de vos donn\u00e9es pour acc\u00e9l\u00e9rer vos d\u00e9cisions strat\u00e9giques Zuora Secure Data Share for Snowflake \u00e9limine les d\u00e9veloppements fastidieux et transf\u00e8re rapidement vos donn\u00e9es Zuora dans Snowflake. Ce module donne \u00e0 votre \u00e9quipe la possibilit\u00e9 d\u2019utiliser sa propre BI pour les m\u00e9triques inter-syst\u00e8mes, tout en tirant [&hellip;]<\/p>\n","protected":false},"author":242,"featured_media":0,"parent":186608,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"content_type":[],"industry":[],"persona":[],"product_line":[],"topic":[],"class_list":["post-203985","page","type-page","status-publish","hentry"],"acf":{"smart_filters_taxonomy_filters":"none"},"_links":{"self":[{"href":"https:\/\/www.zuora.com\/fr\/wp-json\/wp\/v2\/pages\/203985","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zuora.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.zuora.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.zuora.com\/fr\/wp-json\/wp\/v2\/users\/242"}],"replies":[{"embeddable":true,"href":"https:\/\/www.zuora.com\/fr\/wp-json\/wp\/v2\/comments?post=203985"}],"version-history":[{"count":0,"href":"https:\/\/www.zuora.com\/fr\/wp-json\/wp\/v2\/pages\/203985\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/www.zuora.com\/fr\/wp-json\/wp\/v2\/pages\/186608"}],"wp:attachment":[{"href":"https:\/\/www.zuora.com\/fr\/wp-json\/wp\/v2\/media?parent=203985"}],"wp:term":[{"taxonomy":"content_type","embeddable":true,"href":"https:\/\/www.zuora.com\/fr\/wp-json\/wp\/v2\/content_type?post=203985"},{"taxonomy":"industry","embeddable":true,"href":"https:\/\/www.zuora.com\/fr\/wp-json\/wp\/v2\/industry?post=203985"},{"taxonomy":"persona","embeddable":true,"href":"https:\/\/www.zuora.com\/fr\/wp-json\/wp\/v2\/persona?post=203985"},{"taxonomy":"product_line","embeddable":true,"href":"https:\/\/www.zuora.com\/fr\/wp-json\/wp\/v2\/product_line?post=203985"},{"taxonomy":"topic","embeddable":true,"href":"https:\/\/www.zuora.com\/fr\/wp-json\/wp\/v2\/topic?post=203985"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}