{"id":191341,"date":"2019-05-16T13:56:37","date_gmt":"2019-05-16T20:56:37","guid":{"rendered":"https:\/\/sboxtest.zuora.com\/about\/"},"modified":"2023-10-04T05:57:14","modified_gmt":"2023-10-04T12:57:14","slug":"about","status":"publish","type":"page","link":"https:\/\/www.zuora.com\/fr\/about\/","title":{"rendered":"&Agrave; propos | Zuora"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"191341\" class=\"elementor elementor-191341 elementor-62950\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-325329d0 elementor-section-stretched elementor-reverse-tablet elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"325329d0\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5822a5fa\" data-id=\"5822a5fa\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-64e2ca8 elementor-widget elementor-widget-heading\" data-id=\"64e2ca8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">&Agrave; PROPOS DE ZUORA<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-355bef6f elementor-widget elementor-widget-heading\" data-id=\"355bef6f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Les abonnements <br \/>ne sont que le commencement.<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-982fd7d elementor-widget__width-initial elementor-widget-tablet__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"982fd7d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>De la gestion des abonnements \u00e0 la mon\u00e9tisation, nous aidons les entreprises innovantes \u00e0 d\u00e9velopper et \u00e0 mon\u00e9tiser des relations num\u00e9riques directes.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-77433f0c elementor-hidden-mobile elementor-hidden-tablet\" data-id=\"77433f0c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-60864e40 elementor-widget elementor-widget-image\" data-id=\"60864e40\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1031\" height=\"630\" src=\"https:\/\/www.zuora.com\/wp-content\/uploads\/2022\/09\/about-hero-2.png\" class=\"attachment-full size-full wp-image-192017\" alt=\"\" srcset=\"https:\/\/www.zuora.com\/wp-content\/uploads\/2022\/09\/about-hero-2.png 1031w, https:\/\/www.zuora.com\/wp-content\/uploads\/2022\/09\/about-hero-2-640x391.png 640w, https:\/\/www.zuora.com\/wp-content\/uploads\/2022\/09\/about-hero-2-768x469.png 768w\" sizes=\"(max-width: 1031px) 100vw, 1031px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2a0997ff elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2a0997ff\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-510dd2de\" data-id=\"510dd2de\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3a787319 elementor-widget__width-initial elementor-widget-tablet__width-initial elementor-widget-mobile__width-initial elementor-widget elementor-widget-heading\" data-id=\"3a787319\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">&Agrave; propos de Zuora,&nbsp;Inc.<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-44756de5 elementor-widget elementor-widget-text-editor\" data-id=\"44756de5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Il y a 15\u00a0ans, Zuora est n\u00e9 d\u2019une vision d\u2019une toute nouvelle mani\u00e8re d\u2019op\u00e9rer, o\u00f9 les entreprises se focaliseraient sur la mise \u00e0 disposition de services r\u00e9currents centr\u00e9s sur les personnes plut\u00f4t que sur la vente ponctuelle de produits. C\u2019est ainsi que nous avons invent\u00e9 le terme Subscription Economy\u00ae.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7507d1f5 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7507d1f5\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-6fa9776e\" data-id=\"6fa9776e\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2ad83053 elementor-widget elementor-widget-image\" data-id=\"2ad83053\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"493\" height=\"563\" src=\"https:\/\/www.zuora.com\/wp-content\/uploads\/2022\/09\/about-Tien-Tzuo-2.png\" class=\"attachment-large size-large wp-image-192023\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-51868a27\" data-id=\"51868a27\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-28c5e6fd elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"28c5e6fd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Aujourd\u2019hui, nous voyons d\u2019autres promouvoir et construire des communaut\u00e9s enti\u00e8res autour de ce terme. La Subscription\u00a0Economy ne se r\u00e9sume pas (et ne s\u2019est jamais r\u00e9sum\u00e9e) \u00e0 des business models bas\u00e9s sur les abonnements, mais consiste en des relations directes et r\u00e9currentes avec les clients via n\u2019importe quel business model. Les abonnements ne faisaient qu\u2019effleurer la surface, et d\u00e9sormais, le march\u00e9 reconna\u00eet la Subscription\u00a0Economy pour ce qu\u2019elle est v\u00e9ritablement\u00a0: une \u00e9conomie centr\u00e9e sur les relations. Les entreprises ont r\u00e9alis\u00e9 que la voie de la croissance se trouve dans la cr\u00e9ation de relations num\u00e9riques directes avec leurs clients, et dans le <span style=\"font-weight: 500;\">d\u00e9veloppement et la mon\u00e9tisation de ces relations gr\u00e2ce \u00e0 un ensemble toujours plus important de services num\u00e9riques.<\/span><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-17e72484 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"17e72484\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b75545d\" data-id=\"b75545d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-687879fc elementor-widget elementor-widget-text-editor\" data-id=\"687879fc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Zuora a \u00e9t\u00e9 pr\u00e9sent \u00e0 chaque \u00e9tape de cette \u00e9volution. Nous avons commenc\u00e9 avec Zuora\u00a0Billing, puis avons \u00e9largi notre portefeuille produits prim\u00e9 en y int\u00e9grant Zuora\u00a0Revenue, Zuora\u00a0Collect et Zuora Central\u00a0Platform. Plus r\u00e9cemment, nous avons ajout\u00e9 la plateforme Zephr \u00e0 notre gamme, \u00e9largissant ainsi davantage notre r\u00f4le de hub intelligent capable de mon\u00e9tiser le processus complet, des devis aux encaissements en passant par la comptabilisation des recettes, \u00e0 grande \u00e9chelle. C\u2019est ce que nous appelons la <span style=\"font-weight: 500;\">mon\u00e9tisation<\/span>.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5fc19fde elementor-widget elementor-widget-text-editor\" data-id=\"5fc19fde\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tGr\u00e2ce \u00e0 sa technologie et \u00e0 son expertise de pointe, Zuora aide plus de 1\u00a0000\u00a0entreprises \u00e0 travers le monde, y compris BMC\u00a0Software, Box, Caterpillar, General\u00a0Motors, Penske Media\u00a0Corporation, Schneider\u00a0Electric, Siemens et Zoom, \u00e0 entretenir et \u00e0 mon\u00e9tiser des relations num\u00e9riques directes avec leurs abonn\u00e9s. L\u2019entreprise compte plus de 1\u00a0200\u00a0employ\u00e9s dans le monde, nos ZEO, qui accompagnent ces entreprises dans leur d\u00e9veloppement, leur fonctionnement et leur croissance. Situ\u00e9e dans la Silicon\u00a0Valley, Zuora poss\u00e8de des bureaux aux quatre coins du globe, en Am\u00e9rique du Nord, en Europe, en Chine, en Inde, au Japon et en Australie.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1ca06eab elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1ca06eab\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-22cce4b2\" data-id=\"22cce4b2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-33dca390 elementor-widget-mobile__width-initial elementor-widget elementor-widget-image\" data-id=\"33dca390\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"\/fr\/zuora-brand-transformation\/\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"542\" height=\"468\" src=\"https:\/\/www.zuora.com\/wp-content\/uploads\/2022\/09\/be-zuora-zmark.svg\" class=\"attachment-full size-full wp-image-191935\" alt=\"\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-737e6b1e\" data-id=\"737e6b1e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-157c10f9 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"157c10f9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/www.zuora.com\/fr\/about\/zuora-brand-transformation\/\">En savoir plus sur la <br \/>transformation de la marque Zuora<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-aca8cb0 elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default\" data-id=\"aca8cb0\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-35f295d4\" data-id=\"35f295d4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-307a4573 elementor-widget elementor-widget-template\" data-id=\"307a4573\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<div data-elementor-type=\"page\" data-elementor-id=\"194823\" class=\"elementor elementor-194823 elementor-119153 elementor-119153\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ffc0967 e-flex e-con-boxed e-con e-parent\" data-id=\"ffc0967\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-ef44a7c e-con-full e-flex e-con e-child\" data-id=\"ef44a7c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4b98a2b elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"4b98a2b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Optez pour le succ\u00e8s r\u00e9current<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fa40fcb elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"fa40fcb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Les entreprises s\u2019appuient sur Zuora pour accompagner leur croissance. Parce que votre succ\u00e8s est aussi le n\u00f4tre, nous avons \u00e0 c\u0153ur de r\u00e9pondre \u00e0 vos plus grands d\u00e9fis. Notre technologie s\u2019adapte \u00e0 votre mod\u00e8le \u00e9conomique, quel qu\u2019il soit : par abonnement, \u00e0 la consommation, \u00e0 l\u2019usage, hybride, \u2026 A nos c\u00f4t\u00e9s, mon\u00e9tisez l\u2019int\u00e9gralit\u00e9 de vos services.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-40cbdfe e-flex e-con-boxed e-con e-child\" data-id=\"40cbdfe\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-500ef5d elementor-widget__width-auto elementor-widget elementor-widget-button\" data-id=\"500ef5d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"\/fr\/resources\/demo-on-demand\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir une d\u00e9mo<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-289bfe7 elementor-widget__width-auto elementor-widget elementor-widget-button\" data-id=\"289bfe7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"\/fr\/talk-to-sales\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Parler \u00e0 un expert<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3b22a68 e-con-full e-flex e-con e-child\" data-id=\"3b22a68\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-f6f141c e-flex e-con-boxed e-con e-child\" data-id=\"f6f141c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-1ce8245 e-con-full e-flex e-con e-child\" data-id=\"1ce8245\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-addadb5 e-flex e-con-boxed e-con e-child\" data-id=\"addadb5\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c1a01ae elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"c1a01ae\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Envie de mener le changement?<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-eab30f0 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"eab30f0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Int\u00e9grez notre \u00e9quipe internationale d\u00e9di\u00e9e \u00e0 la m\u00e9tamorphose des entreprises leaders \u00e0 l&rsquo;\u00e9chelle globale.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8c2afe7 elementor-position-inline-end elementor-widget__width-auto elementor-view-default elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"8c2afe7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"\/fr\/careers\/\" class=\"elementor-icon\" tabindex=\"-1\" aria-label=\"Explorer vos opportunit\u00e9s\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-arrow-right\"><\/i>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<a href=\"\/fr\/careers\/\" >\n\t\t\t\t\t\t\tExplorer vos opportunit\u00e9s\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>&Agrave; PROPOS DE ZUORA Les abonnements ne sont que le commencement. De la gestion des abonnements \u00e0 la mon\u00e9tisation, nous aidons les entreprises innovantes \u00e0 d\u00e9velopper et \u00e0 mon\u00e9tiser des relations num\u00e9riques directes. &Agrave; propos de Zuora,&nbsp;Inc. Il y a 15\u00a0ans, Zuora est n\u00e9 d\u2019une vision d\u2019une toute nouvelle mani\u00e8re d\u2019op\u00e9rer, o\u00f9 les entreprises se [&hellip;]<\/p>\n","protected":false},"author":227,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"content_type":[],"industry":[],"persona":[],"product_line":[],"topic":[],"class_list":["post-191341","page","type-page","status-publish","hentry"],"acf":{"smart_filters_taxonomy_filters":"none"},"_links":{"self":[{"href":"https:\/\/www.zuora.com\/fr\/wp-json\/wp\/v2\/pages\/191341","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zuora.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.zuora.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.zuora.com\/fr\/wp-json\/wp\/v2\/users\/227"}],"replies":[{"embeddable":true,"href":"https:\/\/www.zuora.com\/fr\/wp-json\/wp\/v2\/comments?post=191341"}],"version-history":[{"count":0,"href":"https:\/\/www.zuora.com\/fr\/wp-json\/wp\/v2\/pages\/191341\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.zuora.com\/fr\/wp-json\/wp\/v2\/media?parent=191341"}],"wp:term":[{"taxonomy":"content_type","embeddable":true,"href":"https:\/\/www.zuora.com\/fr\/wp-json\/wp\/v2\/content_type?post=191341"},{"taxonomy":"industry","embeddable":true,"href":"https:\/\/www.zuora.com\/fr\/wp-json\/wp\/v2\/industry?post=191341"},{"taxonomy":"persona","embeddable":true,"href":"https:\/\/www.zuora.com\/fr\/wp-json\/wp\/v2\/persona?post=191341"},{"taxonomy":"product_line","embeddable":true,"href":"https:\/\/www.zuora.com\/fr\/wp-json\/wp\/v2\/product_line?post=191341"},{"taxonomy":"topic","embeddable":true,"href":"https:\/\/www.zuora.com\/fr\/wp-json\/wp\/v2\/topic?post=191341"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}